{"id":2985,"count":0,"description":"","link":"http:\/\/www.fedejewels.com\/blog\/tag\/ultrasonic-tank-level-sensor-426b-ad6cfc\/","name":"Ultrasonic Tank Level Sensor","slug":"ultrasonic-tank-level-sensor-426b-ad6cfc","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.fedejewels.com\/blog\/wp-json\/wp\/v2\/tags\/2985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.fedejewels.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.fedejewels.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.fedejewels.com\/blog\/wp-json\/wp\/v2\/posts?tags=2985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}